{"id":14900,"date":"2019-12-05T11:44:27","date_gmt":"2019-12-05T10:44:27","guid":{"rendered":"http:\/\/www.clubmaritimomelilla.es\/clmar\/?p=14900"},"modified":"2019-12-05T11:44:27","modified_gmt":"2019-12-05T10:44:27","slug":"la-jornada-inaugural-del-campeonato-de-espana-de-laser-4-7-juvenil-que-hasta-el-domingo-se-celebra-en-la-ciudad-autonoma-de-melilla-organizado-por-su-real-club-maritimo-se-ha-desarrollado-segun-lo-p","status":"publish","type":"post","link":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/la-jornada-inaugural-del-campeonato-de-espana-de-laser-4-7-juvenil-que-hasta-el-domingo-se-celebra-en-la-ciudad-autonoma-de-melilla-organizado-por-su-real-club-maritimo-se-ha-desarrollado-segun-lo-p\/","title":{"rendered":"La jornada inaugural del Campeonato de Espa\u00f1a de Laser 4.7 juvenil, que hasta el domingo se celebra en la ciudad aut\u00f3noma de Melilla organizado por su Real Club Mar\u00edtimo, se ha desarrollado seg\u00fan lo previsto. Todos los regatistas y equipos auton\u00f3micos se encuentran en Melilla, donde hoy se ha procedido a las mediciones oficiales y a la inscripci\u00f3n de los participantes. En total competir\u00e1n 118 regatistas, de las categor\u00edas sub16 y sub18, representando a diez comunidades aut\u00f3nomas y a la ciudad de Melilla.  Las mediciones, junto a los preparativos para la competici\u00f3n y los entrenamientos ha ocupado el tiempo de la flota durante toda la jornada de este mi\u00e9rcoles en el Real Club Maritimo de Melilla.  Una jornada en la que una tormenta ha sido la gran protagonista, que ha sorprendido a la flota tanto en el campo de regatas como en el proceso de inscripci\u00f3n. Pero sin incidencias, convirti\u00e9ndose en el aspecto m\u00e1s comentado durante el almuerzo de los regatistas.  Desde ma\u00f1ana jueves se suceder\u00e1n cuatro jornadas de regata. Las dos primeras, jueves y viernes, est\u00e1n programadas seis mangas clasificatorias. A partir del s\u00e1bado, la flota quedar\u00e1 dividida en grupo Oro y Plata.  En total se decidir\u00e1n cinco t\u00edtulos nacionales, los masculinos y femeninos en sub16 y sub18, adem\u00e1s del campeonato por comunidades aut\u00f3nomas. Para luchar por este \u00faltimo t\u00edtulo, los equipos auton\u00f3micos de Baleares y Comunidad Valenciana son los grandes favoritos. Melilla cuenta con un equipo formado por cuatro regatistas del Real Club Mar\u00edtimo de Melilla. Miguel Due\u00f1as, Pablo Cervilla, Andr\u00e9s Sarri\u00e1 y Miguel Angel Weil"},"content":{"rendered":"<div>La jornada inaugural del Campeonato de Espa\u00f1a de Laser 4.7 juvenil, que hasta el domingo se celebra en la ciudad aut\u00f3noma de Melilla organizado por su Real Club Mar\u00edtimo, se ha desarrollado seg\u00fan lo previsto.<\/div>\n<div>Todos los regatistas y equipos auton\u00f3micos se encuentran en Melilla, donde hoy se ha procedido a las mediciones oficiales y a la inscripci\u00f3n de los participantes. En total competir\u00e1n 118 regatistas, de las categor\u00edas sub16 y sub18, representando a diez comunidades aut\u00f3nomas y a la ciudad de Melilla.<\/div>\n<div>Las mediciones, junto a los preparativos para la competici\u00f3n y los entrenamientos ha ocupado el tiempo de la flota durante toda la jornada de este mi\u00e9rcoles en el Real Club Maritimo de Melilla.<\/div>\n<div>Una jornada en la que una tormenta ha sido la gran protagonista, que ha sorprendido a la flota tanto en el campo de regatas como en el proceso de inscripci\u00f3n. Pero sin incidencias, convirti\u00e9ndose en el aspecto m\u00e1s comentado durante el almuerzo de los regatistas.<\/div>\n<div>Desde ma\u00f1ana jueves se suceder\u00e1n cuatro jornadas de regata. Las dos primeras, jueves y viernes, est\u00e1n programadas seis mangas clasificatorias. A partir del s\u00e1bado, la flota quedar\u00e1 dividida en grupo Oro y Plata.<\/div>\n<div>En total se decidir\u00e1n cinco t\u00edtulos nacionales, los masculinos y femeninos en sub16 y sub18, adem\u00e1s del campeonato por comunidades aut\u00f3nomas. Para luchar por este \u00faltimo t\u00edtulo, los equipos auton\u00f3micos de Baleares y Comunidad Valenciana son los grandes favoritos.<\/div>\n<div>Melilla cuenta con un equipo formado por cuatro regatistas del Real Club Mar\u00edtimo de Melilla. Miguel Due\u00f1as, Pablo Cervilla, Andr\u00e9s Sarri\u00e1 y Miguel Angel Weil.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La jornada inaugural del Campeonato de Espa\u00f1a de Laser 4.7 juvenil, que hasta el domingo se celebra en la ciudad aut\u00f3noma de Melilla organizado por su Real Club Mar\u00edtimo, se ha desarrollado seg\u00fan lo previsto. Todos los regatistas y equipos auton\u00f3micos se encuentran en Melilla, donde hoy se ha procedido a las mediciones oficiales y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14901,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[40,38],"tags":[],"class_list":["post-14900","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-club","category-nautica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La jornada inaugural del Campeonato de Espa\u00f1a de Laser 4.7 juvenil, que hasta el domingo se celebra en la ciudad aut\u00f3noma de Melilla organizado por su Real Club Mar\u00edtimo, se ha desarrollado seg\u00fan lo previsto. Todos los regatistas y equipos auton\u00f3micos se encuentran en Melilla, donde hoy se ha procedido a las mediciones oficiales y a la inscripci\u00f3n de los participantes. En total competir\u00e1n 118 regatistas, de las categor\u00edas sub16 y sub18, representando a diez comunidades aut\u00f3nomas y a la ciudad de Melilla. Las mediciones, junto a los preparativos para la competici\u00f3n y los entrenamientos ha ocupado el tiempo de la flota durante toda la jornada de este mi\u00e9rcoles en el Real Club Maritimo de Melilla. Una jornada en la que una tormenta ha sido la gran protagonista, que ha sorprendido a la flota tanto en el campo de regatas como en el proceso de inscripci\u00f3n. Pero sin incidencias, convirti\u00e9ndose en el aspecto m\u00e1s comentado durante el almuerzo de los regatistas. Desde ma\u00f1ana jueves se suceder\u00e1n cuatro jornadas de regata. Las dos primeras, jueves y viernes, est\u00e1n programadas seis mangas clasificatorias. A partir del s\u00e1bado, la flota quedar\u00e1 dividida en grupo Oro y Plata. En total se decidir\u00e1n cinco t\u00edtulos nacionales, los masculinos y femeninos en sub16 y sub18, adem\u00e1s del campeonato por comunidades aut\u00f3nomas. Para luchar por este \u00faltimo t\u00edtulo, los equipos auton\u00f3micos de Baleares y Comunidad Valenciana son los grandes favoritos. Melilla cuenta con un equipo formado por cuatro regatistas del Real Club Mar\u00edtimo de Melilla. Miguel Due\u00f1as, Pablo Cervilla, Andr\u00e9s Sarri\u00e1 y Miguel Angel Weil - Real Club Mar\u00edtimo de Melilla<\/title>\n<meta name=\"description\" content=\"La jornada inaugural del Campeonato de Espa\u00f1a de Laser 4.7 juvenil, que hasta el domingo se celebra en la ciudad aut\u00f3noma de Melilla organizado por su Real Club Mar\u00edtimo, se ha desarrollado seg\u00fan lo previsto. Todos los regatistas y equipos auton\u00f3micos se encuentran en Melilla, donde hoy se ha procedido a las mediciones oficiales y a la inscripci\u00f3n de los participantes. En total competir\u00e1n 118 regatistas, de las categor\u00edas sub16 y sub18, representando a diez comunidades aut\u00f3nomas y a la ciudad de Melilla. Las mediciones, junto a los preparativos para la competici\u00f3n y los entrenamientos ha ocupado el tiempo de la flota durante toda la jornada de este mi\u00e9rcoles en el Real Club Maritimo de Melilla. Una jornada en la que una tormenta ha sido la gran protagonista, que ha sorprendido a la flota tanto en el campo de regatas como en el proceso de inscripci\u00f3n. Pero sin incidencias, convirti\u00e9ndose en el aspecto m\u00e1s comentado durante el almuerzo de los regatistas. Desde ma\u00f1ana jueves se suceder\u00e1n cuatro jornadas de regata. Las dos primeras, jueves y viernes, est\u00e1n programadas seis mangas clasificatorias. A partir del s\u00e1bado, la flota quedar\u00e1 dividida en grupo Oro y Plata. En total se decidir\u00e1n cinco t\u00edtulos nacionales, los masculinos y femeninos en sub16 y sub18, adem\u00e1s del campeonato por comunidades aut\u00f3nomas. Para luchar por este \u00faltimo t\u00edtulo, los equipos auton\u00f3micos de Baleares y Comunidad Valenciana son los grandes favoritos. Melilla cuenta con un equipo formado por cuatro regatistas del Real Club Mar\u00edtimo de Melilla. Miguel Due\u00f1as, Pablo Cervilla, Andr\u00e9s Sarri\u00e1 y Miguel Angel Weil -\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.realclubmaritimomelilla.es\/clmar\/la-jornada-inaugural-del-campeonato-de-espana-de-laser-4-7-juvenil-que-hasta-el-domingo-se-celebra-en-la-ciudad-autonoma-de-melilla-organizado-por-su-real-club-maritimo-se-ha-desarrollado-segun-lo-p\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La jornada inaugural del Campeonato de Espa\u00f1a de Laser 4.7 juvenil, que hasta el domingo se celebra en la ciudad aut\u00f3noma de Melilla organizado por su Real Club Mar\u00edtimo, se ha desarrollado seg\u00fan lo previsto. Todos los regatistas y equipos auton\u00f3micos se encuentran en Melilla, donde hoy se ha procedido a las mediciones oficiales y a la inscripci\u00f3n de los participantes. En total competir\u00e1n 118 regatistas, de las categor\u00edas sub16 y sub18, representando a diez comunidades aut\u00f3nomas y a la ciudad de Melilla. Las mediciones, junto a los preparativos para la competici\u00f3n y los entrenamientos ha ocupado el tiempo de la flota durante toda la jornada de este mi\u00e9rcoles en el Real Club Maritimo de Melilla. Una jornada en la que una tormenta ha sido la gran protagonista, que ha sorprendido a la flota tanto en el campo de regatas como en el proceso de inscripci\u00f3n. Pero sin incidencias, convirti\u00e9ndose en el aspecto m\u00e1s comentado durante el almuerzo de los regatistas. Desde ma\u00f1ana jueves se suceder\u00e1n cuatro jornadas de regata. Las dos primeras, jueves y viernes, est\u00e1n programadas seis mangas clasificatorias. A partir del s\u00e1bado, la flota quedar\u00e1 dividida en grupo Oro y Plata. En total se decidir\u00e1n cinco t\u00edtulos nacionales, los masculinos y femeninos en sub16 y sub18, adem\u00e1s del campeonato por comunidades aut\u00f3nomas. Para luchar por este \u00faltimo t\u00edtulo, los equipos auton\u00f3micos de Baleares y Comunidad Valenciana son los grandes favoritos. Melilla cuenta con un equipo formado por cuatro regatistas del Real Club Mar\u00edtimo de Melilla. Miguel Due\u00f1as, Pablo Cervilla, Andr\u00e9s Sarri\u00e1 y Miguel Angel Weil - Real Club Mar\u00edtimo de Melilla\" \/>\n<meta property=\"og:description\" content=\"La jornada inaugural del Campeonato de Espa\u00f1a de Laser 4.7 juvenil, que hasta el domingo se celebra en la ciudad aut\u00f3noma de Melilla organizado por su Real Club Mar\u00edtimo, se ha desarrollado seg\u00fan lo previsto. Todos los regatistas y equipos auton\u00f3micos se encuentran en Melilla, donde hoy se ha procedido a las mediciones oficiales y a la inscripci\u00f3n de los participantes. En total competir\u00e1n 118 regatistas, de las categor\u00edas sub16 y sub18, representando a diez comunidades aut\u00f3nomas y a la ciudad de Melilla. Las mediciones, junto a los preparativos para la competici\u00f3n y los entrenamientos ha ocupado el tiempo de la flota durante toda la jornada de este mi\u00e9rcoles en el Real Club Maritimo de Melilla. Una jornada en la que una tormenta ha sido la gran protagonista, que ha sorprendido a la flota tanto en el campo de regatas como en el proceso de inscripci\u00f3n. Pero sin incidencias, convirti\u00e9ndose en el aspecto m\u00e1s comentado durante el almuerzo de los regatistas. Desde ma\u00f1ana jueves se suceder\u00e1n cuatro jornadas de regata. Las dos primeras, jueves y viernes, est\u00e1n programadas seis mangas clasificatorias. A partir del s\u00e1bado, la flota quedar\u00e1 dividida en grupo Oro y Plata. En total se decidir\u00e1n cinco t\u00edtulos nacionales, los masculinos y femeninos en sub16 y sub18, adem\u00e1s del campeonato por comunidades aut\u00f3nomas. Para luchar por este \u00faltimo t\u00edtulo, los equipos auton\u00f3micos de Baleares y Comunidad Valenciana son los grandes favoritos. Melilla cuenta con un equipo formado por cuatro regatistas del Real Club Mar\u00edtimo de Melilla. Miguel Due\u00f1as, Pablo Cervilla, Andr\u00e9s Sarri\u00e1 y Miguel Angel Weil -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.realclubmaritimomelilla.es\/clmar\/la-jornada-inaugural-del-campeonato-de-espana-de-laser-4-7-juvenil-que-hasta-el-domingo-se-celebra-en-la-ciudad-autonoma-de-melilla-organizado-por-su-real-club-maritimo-se-ha-desarrollado-segun-lo-p\/\" \/>\n<meta property=\"og:site_name\" content=\"Real Club Mar\u00edtimo de Melilla\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Real-Club-Mar%c3%adtimo-de-Melilla-588495841234214\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-05T10:44:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.realclubmaritimomelilla.es\/clmar\/wp-content\/uploads\/2019\/12\/jornada-mediciones.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2016\" \/>\n\t<meta property=\"og:image:height\" content=\"1512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"RCMMelilla\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@nauticarcmm\" \/>\n<meta name=\"twitter:site\" content=\"@nauticarcmm\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"RCMMelilla\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.realclubmaritimomelilla.es\\\/clmar\\\/la-jornada-inaugural-del-campeonato-de-espana-de-laser-4-7-juvenil-que-hasta-el-domingo-se-celebra-en-la-ciudad-autonoma-de-melilla-organizado-por-su-real-club-maritimo-se-ha-desarrollado-segun-lo-p\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.realclubmaritimomelilla.es\\\/clmar\\\/la-jornada-inaugural-del-campeonato-de-espana-de-laser-4-7-juvenil-que-hasta-el-domingo-se-celebra-en-la-ciudad-autonoma-de-melilla-organizado-por-su-real-club-maritimo-se-ha-desarrollado-segun-lo-p\\\/\"},\"author\":{\"name\":\"RCMMelilla\",\"@id\":\"https:\\\/\\\/www.realclubmaritimomelilla.es\\\/clmar\\\/#\\\/schema\\\/person\\\/ebaa3713496dc6d48c872452e73a8e79\"},\"headline\":\"La jornada inaugural del Campeonato de Espa\u00f1a de Laser 4.7 juvenil, que hasta el domingo se celebra en la ciudad aut\u00f3noma de Melilla organizado por su Real Club Mar\u00edtimo, se ha desarrollado seg\u00fan lo previsto. Todos los regatistas y equipos auton\u00f3micos se encuentran en Melilla, donde hoy se ha procedido a las mediciones oficiales y a la inscripci\u00f3n de los participantes. En total competir\u00e1n 118 regatistas, de las categor\u00edas sub16 y sub18, representando a diez comunidades aut\u00f3nomas y a la ciudad de Melilla. Las mediciones, junto a los preparativos para la competici\u00f3n y los entrenamientos ha ocupado el tiempo de la flota durante toda la jornada de este mi\u00e9rcoles en el Real Club Maritimo de Melilla. Una jornada en la que una tormenta ha sido la gran protagonista, que ha sorprendido a la flota tanto en el campo de regatas como en el proceso de inscripci\u00f3n. Pero sin incidencias, convirti\u00e9ndose en el aspecto m\u00e1s comentado durante el almuerzo de los regatistas. Desde ma\u00f1ana jueves se suceder\u00e1n cuatro jornadas de regata. Las dos primeras, jueves y viernes, est\u00e1n programadas seis mangas clasificatorias. A partir del s\u00e1bado, la flota quedar\u00e1 dividida en grupo Oro y Plata. En total se decidir\u00e1n cinco t\u00edtulos nacionales, los masculinos y femeninos en sub16 y sub18, adem\u00e1s del campeonato por comunidades aut\u00f3nomas. Para luchar por este \u00faltimo t\u00edtulo, los equipos auton\u00f3micos de Baleares y Comunidad Valenciana son los grandes favoritos. Melilla cuenta con un equipo formado por cuatro regatistas del Real Club Mar\u00edtimo de Melilla. Miguel Due\u00f1as, Pablo Cervilla, Andr\u00e9s Sarri\u00e1 y Miguel Angel Weil\",\"datePublished\":\"2019-12-05T10:44:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.realclubmaritimomelilla.es\\\/clmar\\\/la-jornada-inaugural-del-campeonato-de-espana-de-laser-4-7-juvenil-que-hasta-el-domingo-se-celebra-en-la-ciudad-autonoma-de-melilla-organizado-por-su-real-club-maritimo-se-ha-desarrollado-segun-lo-p\\\/\"},\"wordCount\":566,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.realclubmaritimomelilla.es\\\/clmar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.realclubmaritimomelilla.es\\\/clmar\\\/la-jornada-inaugural-del-campeonato-de-espana-de-laser-4-7-juvenil-que-hasta-el-domingo-se-celebra-en-la-ciudad-autonoma-de-melilla-organizado-por-su-real-club-maritimo-se-ha-desarrollado-segun-lo-p\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.realclubmaritimomelilla.es\\\/clmar\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/jornada-mediciones.jpg\",\"articleSection\":[\"Club\",\"N\u00e1utica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.realclubmaritimomelilla.es\\\/clmar\\\/la-jornada-inaugural-del-campeonato-de-espana-de-laser-4-7-juvenil-que-hasta-el-domingo-se-celebra-en-la-ciudad-autonoma-de-melilla-organizado-por-su-real-club-maritimo-se-ha-desarrollado-segun-lo-p\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.realclubmaritimomelilla.es\\\/clmar\\\/la-jornada-inaugural-del-campeonato-de-espana-de-laser-4-7-juvenil-que-hasta-el-domingo-se-celebra-en-la-ciudad-autonoma-de-melilla-organizado-por-su-real-club-maritimo-se-ha-desarrollado-segun-lo-p\\\/\",\"url\":\"https:\\\/\\\/www.realclubmaritimomelilla.es\\\/clmar\\\/la-jornada-inaugural-del-campeonato-de-espana-de-laser-4-7-juvenil-que-hasta-el-domingo-se-celebra-en-la-ciudad-autonoma-de-melilla-organizado-por-su-real-club-maritimo-se-ha-desarrollado-segun-lo-p\\\/\",\"name\":\"La jornada inaugural del Campeonato de Espa\u00f1a de Laser 4.7 juvenil, que hasta el domingo se celebra en la ciudad aut\u00f3noma de Melilla organizado por su Real Club Mar\u00edtimo, se ha desarrollado seg\u00fan lo previsto. Todos los regatistas y equipos auton\u00f3micos se encuentran en Melilla, donde hoy se ha procedido a las mediciones oficiales y a la inscripci\u00f3n de los participantes. En total competir\u00e1n 118 regatistas, de las categor\u00edas sub16 y sub18, representando a diez comunidades aut\u00f3nomas y a la ciudad de Melilla. Las mediciones, junto a los preparativos para la competici\u00f3n y los entrenamientos ha ocupado el tiempo de la flota durante toda la jornada de este mi\u00e9rcoles en el Real Club Maritimo de Melilla. Una jornada en la que una tormenta ha sido la gran protagonista, que ha sorprendido a la flota tanto en el campo de regatas como en el proceso de inscripci\u00f3n. Pero sin incidencias, convirti\u00e9ndose en el aspecto m\u00e1s comentado durante el almuerzo de los regatistas. Desde ma\u00f1ana jueves se suceder\u00e1n cuatro jornadas de regata. Las dos primeras, jueves y viernes, est\u00e1n programadas seis mangas clasificatorias. A partir del s\u00e1bado, la flota quedar\u00e1 dividida en grupo Oro y Plata. En total se decidir\u00e1n cinco t\u00edtulos nacionales, los masculinos y femeninos en sub16 y sub18, adem\u00e1s del campeonato por comunidades aut\u00f3nomas. Para luchar por este \u00faltimo t\u00edtulo, los equipos auton\u00f3micos de Baleares y Comunidad Valenciana son los grandes favoritos. Melilla cuenta con un equipo formado por cuatro regatistas del Real Club Mar\u00edtimo de Melilla. Miguel Due\u00f1as, Pablo Cervilla, Andr\u00e9s Sarri\u00e1 y Miguel Angel Weil - Real Club Mar\u00edtimo de Melilla\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.realclubmaritimomelilla.es\\\/clmar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.realclubmaritimomelilla.es\\\/clmar\\\/la-jornada-inaugural-del-campeonato-de-espana-de-laser-4-7-juvenil-que-hasta-el-domingo-se-celebra-en-la-ciudad-autonoma-de-melilla-organizado-por-su-real-club-maritimo-se-ha-desarrollado-segun-lo-p\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.realclubmaritimomelilla.es\\\/clmar\\\/la-jornada-inaugural-del-campeonato-de-espana-de-laser-4-7-juvenil-que-hasta-el-domingo-se-celebra-en-la-ciudad-autonoma-de-melilla-organizado-por-su-real-club-maritimo-se-ha-desarrollado-segun-lo-p\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.realclubmaritimomelilla.es\\\/clmar\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/jornada-mediciones.jpg\",\"datePublished\":\"2019-12-05T10:44:27+00:00\",\"description\":\"La jornada inaugural del Campeonato de Espa\u00f1a de Laser 4.7 juvenil, que hasta el domingo se celebra en la ciudad aut\u00f3noma de Melilla organizado por su Real Club Mar\u00edtimo, se ha desarrollado seg\u00fan lo previsto. Todos los regatistas y equipos auton\u00f3micos se encuentran en Melilla, donde hoy se ha procedido a las mediciones oficiales y a la inscripci\u00f3n de los participantes. En total competir\u00e1n 118 regatistas, de las categor\u00edas sub16 y sub18, representando a diez comunidades aut\u00f3nomas y a la ciudad de Melilla. Las mediciones, junto a los preparativos para la competici\u00f3n y los entrenamientos ha ocupado el tiempo de la flota durante toda la jornada de este mi\u00e9rcoles en el Real Club Maritimo de Melilla. Una jornada en la que una tormenta ha sido la gran protagonista, que ha sorprendido a la flota tanto en el campo de regatas como en el proceso de inscripci\u00f3n. Pero sin incidencias, convirti\u00e9ndose en el aspecto m\u00e1s comentado durante el almuerzo de los regatistas. Desde ma\u00f1ana jueves se suceder\u00e1n cuatro jornadas de regata. Las dos primeras, jueves y viernes, est\u00e1n programadas seis mangas clasificatorias. A partir del s\u00e1bado, la flota quedar\u00e1 dividida en grupo Oro y Plata. En total se decidir\u00e1n cinco t\u00edtulos nacionales, los masculinos y femeninos en sub16 y sub18, adem\u00e1s del campeonato por comunidades aut\u00f3nomas. Para luchar por este \u00faltimo t\u00edtulo, los equipos auton\u00f3micos de Baleares y Comunidad Valenciana son los grandes favoritos. Melilla cuenta con un equipo formado por cuatro regatistas del Real Club Mar\u00edtimo de Melilla. Miguel Due\u00f1as, Pablo Cervilla, Andr\u00e9s Sarri\u00e1 y Miguel Angel Weil -\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.realclubmaritimomelilla.es\\\/clmar\\\/la-jornada-inaugural-del-campeonato-de-espana-de-laser-4-7-juvenil-que-hasta-el-domingo-se-celebra-en-la-ciudad-autonoma-de-melilla-organizado-por-su-real-club-maritimo-se-ha-desarrollado-segun-lo-p\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.realclubmaritimomelilla.es\\\/clmar\\\/la-jornada-inaugural-del-campeonato-de-espana-de-laser-4-7-juvenil-que-hasta-el-domingo-se-celebra-en-la-ciudad-autonoma-de-melilla-organizado-por-su-real-club-maritimo-se-ha-desarrollado-segun-lo-p\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.realclubmaritimomelilla.es\\\/clmar\\\/la-jornada-inaugural-del-campeonato-de-espana-de-laser-4-7-juvenil-que-hasta-el-domingo-se-celebra-en-la-ciudad-autonoma-de-melilla-organizado-por-su-real-club-maritimo-se-ha-desarrollado-segun-lo-p\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.realclubmaritimomelilla.es\\\/clmar\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/jornada-mediciones.jpg\",\"contentUrl\":\"https:\\\/\\\/www.realclubmaritimomelilla.es\\\/clmar\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/jornada-mediciones.jpg\",\"width\":2016,\"height\":1512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.realclubmaritimomelilla.es\\\/clmar\\\/la-jornada-inaugural-del-campeonato-de-espana-de-laser-4-7-juvenil-que-hasta-el-domingo-se-celebra-en-la-ciudad-autonoma-de-melilla-organizado-por-su-real-club-maritimo-se-ha-desarrollado-segun-lo-p\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.realclubmaritimomelilla.es\\\/clmar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La jornada inaugural del Campeonato de Espa\u00f1a de Laser 4.7 juvenil, que hasta el domingo se celebra en la ciudad aut\u00f3noma de Melilla organizado por su Real Club Mar\u00edtimo, se ha desarrollado seg\u00fan lo previsto. Todos los regatistas y equipos auton\u00f3micos se encuentran en Melilla, donde hoy se ha procedido a las mediciones oficiales y a la inscripci\u00f3n de los participantes. En total competir\u00e1n 118 regatistas, de las categor\u00edas sub16 y sub18, representando a diez comunidades aut\u00f3nomas y a la ciudad de Melilla. Las mediciones, junto a los preparativos para la competici\u00f3n y los entrenamientos ha ocupado el tiempo de la flota durante toda la jornada de este mi\u00e9rcoles en el Real Club Maritimo de Melilla. Una jornada en la que una tormenta ha sido la gran protagonista, que ha sorprendido a la flota tanto en el campo de regatas como en el proceso de inscripci\u00f3n. Pero sin incidencias, convirti\u00e9ndose en el aspecto m\u00e1s comentado durante el almuerzo de los regatistas. Desde ma\u00f1ana jueves se suceder\u00e1n cuatro jornadas de regata. Las dos primeras, jueves y viernes, est\u00e1n programadas seis mangas clasificatorias. A partir del s\u00e1bado, la flota quedar\u00e1 dividida en grupo Oro y Plata. En total se decidir\u00e1n cinco t\u00edtulos nacionales, los masculinos y femeninos en sub16 y sub18, adem\u00e1s del campeonato por comunidades aut\u00f3nomas. Para luchar por este \u00faltimo t\u00edtulo, los equipos auton\u00f3micos de Baleares y Comunidad Valenciana son los grandes favoritos. Melilla cuenta con un equipo formado por cuatro regatistas del Real Club Mar\u00edtimo de Melilla. Miguel Due\u00f1as, Pablo Cervilla, Andr\u00e9s Sarri\u00e1 y Miguel Angel Weil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.realclubmaritimomelilla.es\\\/clmar\\\/#website\",\"url\":\"https:\\\/\\\/www.realclubmaritimomelilla.es\\\/clmar\\\/\",\"name\":\"Real Club Mar\u00edtimo de Melilla\",\"description\":\"RCMM\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.realclubmaritimomelilla.es\\\/clmar\\\/#organization\"},\"alternateName\":\"RCMM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.realclubmaritimomelilla.es\\\/clmar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.realclubmaritimomelilla.es\\\/clmar\\\/#organization\",\"name\":\"Real Club Mar\u00edtimo de Melilla\",\"alternateName\":\"RCMM\",\"url\":\"https:\\\/\\\/www.realclubmaritimomelilla.es\\\/clmar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.realclubmaritimomelilla.es\\\/clmar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.realclubmaritimomelilla.es\\\/clmar\\\/wp-content\\\/uploads\\\/logo-club-original-copia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.realclubmaritimomelilla.es\\\/clmar\\\/wp-content\\\/uploads\\\/logo-club-original-copia.jpg\",\"width\":128,\"height\":89,\"caption\":\"Real Club Mar\u00edtimo de Melilla\"},\"image\":{\"@id\":\"https:\\\/\\\/www.realclubmaritimomelilla.es\\\/clmar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Real-Club-Mar\u00edtimo-de-Melilla-588495841234214\\\/\",\"https:\\\/\\\/x.com\\\/nauticarcmm\",\"https:\\\/\\\/www.instagram.com\\\/club_maritimo_melilla\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@realclubmaritimodemelilla4703\",\"https:\\\/\\\/es.wikipedia.org\\\/wiki\\\/Real_Club_Mar\u00edtimo_de_Melilla\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.realclubmaritimomelilla.es\\\/clmar\\\/#\\\/schema\\\/person\\\/ebaa3713496dc6d48c872452e73a8e79\",\"name\":\"RCMMelilla\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df1c24789360fb9308735c4ee556fc2bc5bf924bf01e53043b8b97ba272da33c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df1c24789360fb9308735c4ee556fc2bc5bf924bf01e53043b8b97ba272da33c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df1c24789360fb9308735c4ee556fc2bc5bf924bf01e53043b8b97ba272da33c?s=96&d=mm&r=g\",\"caption\":\"RCMMelilla\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La jornada inaugural del Campeonato de Espa\u00f1a de Laser 4.7 juvenil, que hasta el domingo se celebra en la ciudad aut\u00f3noma de Melilla organizado por su Real Club Mar\u00edtimo, se ha desarrollado seg\u00fan lo previsto. Todos los regatistas y equipos auton\u00f3micos se encuentran en Melilla, donde hoy se ha procedido a las mediciones oficiales y a la inscripci\u00f3n de los participantes. En total competir\u00e1n 118 regatistas, de las categor\u00edas sub16 y sub18, representando a diez comunidades aut\u00f3nomas y a la ciudad de Melilla. Las mediciones, junto a los preparativos para la competici\u00f3n y los entrenamientos ha ocupado el tiempo de la flota durante toda la jornada de este mi\u00e9rcoles en el Real Club Maritimo de Melilla. Una jornada en la que una tormenta ha sido la gran protagonista, que ha sorprendido a la flota tanto en el campo de regatas como en el proceso de inscripci\u00f3n. Pero sin incidencias, convirti\u00e9ndose en el aspecto m\u00e1s comentado durante el almuerzo de los regatistas. Desde ma\u00f1ana jueves se suceder\u00e1n cuatro jornadas de regata. Las dos primeras, jueves y viernes, est\u00e1n programadas seis mangas clasificatorias. A partir del s\u00e1bado, la flota quedar\u00e1 dividida en grupo Oro y Plata. En total se decidir\u00e1n cinco t\u00edtulos nacionales, los masculinos y femeninos en sub16 y sub18, adem\u00e1s del campeonato por comunidades aut\u00f3nomas. Para luchar por este \u00faltimo t\u00edtulo, los equipos auton\u00f3micos de Baleares y Comunidad Valenciana son los grandes favoritos. Melilla cuenta con un equipo formado por cuatro regatistas del Real Club Mar\u00edtimo de Melilla. Miguel Due\u00f1as, Pablo Cervilla, Andr\u00e9s Sarri\u00e1 y Miguel Angel Weil - Real Club Mar\u00edtimo de Melilla","description":"La jornada inaugural del Campeonato de Espa\u00f1a de Laser 4.7 juvenil, que hasta el domingo se celebra en la ciudad aut\u00f3noma de Melilla organizado por su Real Club Mar\u00edtimo, se ha desarrollado seg\u00fan lo previsto. Todos los regatistas y equipos auton\u00f3micos se encuentran en Melilla, donde hoy se ha procedido a las mediciones oficiales y a la inscripci\u00f3n de los participantes. En total competir\u00e1n 118 regatistas, de las categor\u00edas sub16 y sub18, representando a diez comunidades aut\u00f3nomas y a la ciudad de Melilla. Las mediciones, junto a los preparativos para la competici\u00f3n y los entrenamientos ha ocupado el tiempo de la flota durante toda la jornada de este mi\u00e9rcoles en el Real Club Maritimo de Melilla. Una jornada en la que una tormenta ha sido la gran protagonista, que ha sorprendido a la flota tanto en el campo de regatas como en el proceso de inscripci\u00f3n. Pero sin incidencias, convirti\u00e9ndose en el aspecto m\u00e1s comentado durante el almuerzo de los regatistas. Desde ma\u00f1ana jueves se suceder\u00e1n cuatro jornadas de regata. Las dos primeras, jueves y viernes, est\u00e1n programadas seis mangas clasificatorias. A partir del s\u00e1bado, la flota quedar\u00e1 dividida en grupo Oro y Plata. En total se decidir\u00e1n cinco t\u00edtulos nacionales, los masculinos y femeninos en sub16 y sub18, adem\u00e1s del campeonato por comunidades aut\u00f3nomas. Para luchar por este \u00faltimo t\u00edtulo, los equipos auton\u00f3micos de Baleares y Comunidad Valenciana son los grandes favoritos. Melilla cuenta con un equipo formado por cuatro regatistas del Real Club Mar\u00edtimo de Melilla. Miguel Due\u00f1as, Pablo Cervilla, Andr\u00e9s Sarri\u00e1 y Miguel Angel Weil -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/la-jornada-inaugural-del-campeonato-de-espana-de-laser-4-7-juvenil-que-hasta-el-domingo-se-celebra-en-la-ciudad-autonoma-de-melilla-organizado-por-su-real-club-maritimo-se-ha-desarrollado-segun-lo-p\/","og_locale":"es_ES","og_type":"article","og_title":"La jornada inaugural del Campeonato de Espa\u00f1a de Laser 4.7 juvenil, que hasta el domingo se celebra en la ciudad aut\u00f3noma de Melilla organizado por su Real Club Mar\u00edtimo, se ha desarrollado seg\u00fan lo previsto. Todos los regatistas y equipos auton\u00f3micos se encuentran en Melilla, donde hoy se ha procedido a las mediciones oficiales y a la inscripci\u00f3n de los participantes. En total competir\u00e1n 118 regatistas, de las categor\u00edas sub16 y sub18, representando a diez comunidades aut\u00f3nomas y a la ciudad de Melilla. Las mediciones, junto a los preparativos para la competici\u00f3n y los entrenamientos ha ocupado el tiempo de la flota durante toda la jornada de este mi\u00e9rcoles en el Real Club Maritimo de Melilla. Una jornada en la que una tormenta ha sido la gran protagonista, que ha sorprendido a la flota tanto en el campo de regatas como en el proceso de inscripci\u00f3n. Pero sin incidencias, convirti\u00e9ndose en el aspecto m\u00e1s comentado durante el almuerzo de los regatistas. Desde ma\u00f1ana jueves se suceder\u00e1n cuatro jornadas de regata. Las dos primeras, jueves y viernes, est\u00e1n programadas seis mangas clasificatorias. A partir del s\u00e1bado, la flota quedar\u00e1 dividida en grupo Oro y Plata. En total se decidir\u00e1n cinco t\u00edtulos nacionales, los masculinos y femeninos en sub16 y sub18, adem\u00e1s del campeonato por comunidades aut\u00f3nomas. Para luchar por este \u00faltimo t\u00edtulo, los equipos auton\u00f3micos de Baleares y Comunidad Valenciana son los grandes favoritos. Melilla cuenta con un equipo formado por cuatro regatistas del Real Club Mar\u00edtimo de Melilla. Miguel Due\u00f1as, Pablo Cervilla, Andr\u00e9s Sarri\u00e1 y Miguel Angel Weil - Real Club Mar\u00edtimo de Melilla","og_description":"La jornada inaugural del Campeonato de Espa\u00f1a de Laser 4.7 juvenil, que hasta el domingo se celebra en la ciudad aut\u00f3noma de Melilla organizado por su Real Club Mar\u00edtimo, se ha desarrollado seg\u00fan lo previsto. Todos los regatistas y equipos auton\u00f3micos se encuentran en Melilla, donde hoy se ha procedido a las mediciones oficiales y a la inscripci\u00f3n de los participantes. En total competir\u00e1n 118 regatistas, de las categor\u00edas sub16 y sub18, representando a diez comunidades aut\u00f3nomas y a la ciudad de Melilla. Las mediciones, junto a los preparativos para la competici\u00f3n y los entrenamientos ha ocupado el tiempo de la flota durante toda la jornada de este mi\u00e9rcoles en el Real Club Maritimo de Melilla. Una jornada en la que una tormenta ha sido la gran protagonista, que ha sorprendido a la flota tanto en el campo de regatas como en el proceso de inscripci\u00f3n. Pero sin incidencias, convirti\u00e9ndose en el aspecto m\u00e1s comentado durante el almuerzo de los regatistas. Desde ma\u00f1ana jueves se suceder\u00e1n cuatro jornadas de regata. Las dos primeras, jueves y viernes, est\u00e1n programadas seis mangas clasificatorias. A partir del s\u00e1bado, la flota quedar\u00e1 dividida en grupo Oro y Plata. En total se decidir\u00e1n cinco t\u00edtulos nacionales, los masculinos y femeninos en sub16 y sub18, adem\u00e1s del campeonato por comunidades aut\u00f3nomas. Para luchar por este \u00faltimo t\u00edtulo, los equipos auton\u00f3micos de Baleares y Comunidad Valenciana son los grandes favoritos. Melilla cuenta con un equipo formado por cuatro regatistas del Real Club Mar\u00edtimo de Melilla. Miguel Due\u00f1as, Pablo Cervilla, Andr\u00e9s Sarri\u00e1 y Miguel Angel Weil -","og_url":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/la-jornada-inaugural-del-campeonato-de-espana-de-laser-4-7-juvenil-que-hasta-el-domingo-se-celebra-en-la-ciudad-autonoma-de-melilla-organizado-por-su-real-club-maritimo-se-ha-desarrollado-segun-lo-p\/","og_site_name":"Real Club Mar\u00edtimo de Melilla","article_publisher":"https:\/\/www.facebook.com\/Real-Club-Mar%c3%adtimo-de-Melilla-588495841234214\/","article_published_time":"2019-12-05T10:44:27+00:00","og_image":[{"width":2016,"height":1512,"url":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/wp-content\/uploads\/2019\/12\/jornada-mediciones.jpg","type":"image\/jpeg"}],"author":"RCMMelilla","twitter_card":"summary_large_image","twitter_creator":"@nauticarcmm","twitter_site":"@nauticarcmm","twitter_misc":{"Escrito por":"RCMMelilla","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/la-jornada-inaugural-del-campeonato-de-espana-de-laser-4-7-juvenil-que-hasta-el-domingo-se-celebra-en-la-ciudad-autonoma-de-melilla-organizado-por-su-real-club-maritimo-se-ha-desarrollado-segun-lo-p\/#article","isPartOf":{"@id":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/la-jornada-inaugural-del-campeonato-de-espana-de-laser-4-7-juvenil-que-hasta-el-domingo-se-celebra-en-la-ciudad-autonoma-de-melilla-organizado-por-su-real-club-maritimo-se-ha-desarrollado-segun-lo-p\/"},"author":{"name":"RCMMelilla","@id":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/#\/schema\/person\/ebaa3713496dc6d48c872452e73a8e79"},"headline":"La jornada inaugural del Campeonato de Espa\u00f1a de Laser 4.7 juvenil, que hasta el domingo se celebra en la ciudad aut\u00f3noma de Melilla organizado por su Real Club Mar\u00edtimo, se ha desarrollado seg\u00fan lo previsto. Todos los regatistas y equipos auton\u00f3micos se encuentran en Melilla, donde hoy se ha procedido a las mediciones oficiales y a la inscripci\u00f3n de los participantes. En total competir\u00e1n 118 regatistas, de las categor\u00edas sub16 y sub18, representando a diez comunidades aut\u00f3nomas y a la ciudad de Melilla. Las mediciones, junto a los preparativos para la competici\u00f3n y los entrenamientos ha ocupado el tiempo de la flota durante toda la jornada de este mi\u00e9rcoles en el Real Club Maritimo de Melilla. Una jornada en la que una tormenta ha sido la gran protagonista, que ha sorprendido a la flota tanto en el campo de regatas como en el proceso de inscripci\u00f3n. Pero sin incidencias, convirti\u00e9ndose en el aspecto m\u00e1s comentado durante el almuerzo de los regatistas. Desde ma\u00f1ana jueves se suceder\u00e1n cuatro jornadas de regata. Las dos primeras, jueves y viernes, est\u00e1n programadas seis mangas clasificatorias. A partir del s\u00e1bado, la flota quedar\u00e1 dividida en grupo Oro y Plata. En total se decidir\u00e1n cinco t\u00edtulos nacionales, los masculinos y femeninos en sub16 y sub18, adem\u00e1s del campeonato por comunidades aut\u00f3nomas. Para luchar por este \u00faltimo t\u00edtulo, los equipos auton\u00f3micos de Baleares y Comunidad Valenciana son los grandes favoritos. Melilla cuenta con un equipo formado por cuatro regatistas del Real Club Mar\u00edtimo de Melilla. Miguel Due\u00f1as, Pablo Cervilla, Andr\u00e9s Sarri\u00e1 y Miguel Angel Weil","datePublished":"2019-12-05T10:44:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/la-jornada-inaugural-del-campeonato-de-espana-de-laser-4-7-juvenil-que-hasta-el-domingo-se-celebra-en-la-ciudad-autonoma-de-melilla-organizado-por-su-real-club-maritimo-se-ha-desarrollado-segun-lo-p\/"},"wordCount":566,"commentCount":0,"publisher":{"@id":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/#organization"},"image":{"@id":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/la-jornada-inaugural-del-campeonato-de-espana-de-laser-4-7-juvenil-que-hasta-el-domingo-se-celebra-en-la-ciudad-autonoma-de-melilla-organizado-por-su-real-club-maritimo-se-ha-desarrollado-segun-lo-p\/#primaryimage"},"thumbnailUrl":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/wp-content\/uploads\/2019\/12\/jornada-mediciones.jpg","articleSection":["Club","N\u00e1utica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.realclubmaritimomelilla.es\/clmar\/la-jornada-inaugural-del-campeonato-de-espana-de-laser-4-7-juvenil-que-hasta-el-domingo-se-celebra-en-la-ciudad-autonoma-de-melilla-organizado-por-su-real-club-maritimo-se-ha-desarrollado-segun-lo-p\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/la-jornada-inaugural-del-campeonato-de-espana-de-laser-4-7-juvenil-que-hasta-el-domingo-se-celebra-en-la-ciudad-autonoma-de-melilla-organizado-por-su-real-club-maritimo-se-ha-desarrollado-segun-lo-p\/","url":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/la-jornada-inaugural-del-campeonato-de-espana-de-laser-4-7-juvenil-que-hasta-el-domingo-se-celebra-en-la-ciudad-autonoma-de-melilla-organizado-por-su-real-club-maritimo-se-ha-desarrollado-segun-lo-p\/","name":"La jornada inaugural del Campeonato de Espa\u00f1a de Laser 4.7 juvenil, que hasta el domingo se celebra en la ciudad aut\u00f3noma de Melilla organizado por su Real Club Mar\u00edtimo, se ha desarrollado seg\u00fan lo previsto. Todos los regatistas y equipos auton\u00f3micos se encuentran en Melilla, donde hoy se ha procedido a las mediciones oficiales y a la inscripci\u00f3n de los participantes. En total competir\u00e1n 118 regatistas, de las categor\u00edas sub16 y sub18, representando a diez comunidades aut\u00f3nomas y a la ciudad de Melilla. Las mediciones, junto a los preparativos para la competici\u00f3n y los entrenamientos ha ocupado el tiempo de la flota durante toda la jornada de este mi\u00e9rcoles en el Real Club Maritimo de Melilla. Una jornada en la que una tormenta ha sido la gran protagonista, que ha sorprendido a la flota tanto en el campo de regatas como en el proceso de inscripci\u00f3n. Pero sin incidencias, convirti\u00e9ndose en el aspecto m\u00e1s comentado durante el almuerzo de los regatistas. Desde ma\u00f1ana jueves se suceder\u00e1n cuatro jornadas de regata. Las dos primeras, jueves y viernes, est\u00e1n programadas seis mangas clasificatorias. A partir del s\u00e1bado, la flota quedar\u00e1 dividida en grupo Oro y Plata. En total se decidir\u00e1n cinco t\u00edtulos nacionales, los masculinos y femeninos en sub16 y sub18, adem\u00e1s del campeonato por comunidades aut\u00f3nomas. Para luchar por este \u00faltimo t\u00edtulo, los equipos auton\u00f3micos de Baleares y Comunidad Valenciana son los grandes favoritos. Melilla cuenta con un equipo formado por cuatro regatistas del Real Club Mar\u00edtimo de Melilla. Miguel Due\u00f1as, Pablo Cervilla, Andr\u00e9s Sarri\u00e1 y Miguel Angel Weil - Real Club Mar\u00edtimo de Melilla","isPartOf":{"@id":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/la-jornada-inaugural-del-campeonato-de-espana-de-laser-4-7-juvenil-que-hasta-el-domingo-se-celebra-en-la-ciudad-autonoma-de-melilla-organizado-por-su-real-club-maritimo-se-ha-desarrollado-segun-lo-p\/#primaryimage"},"image":{"@id":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/la-jornada-inaugural-del-campeonato-de-espana-de-laser-4-7-juvenil-que-hasta-el-domingo-se-celebra-en-la-ciudad-autonoma-de-melilla-organizado-por-su-real-club-maritimo-se-ha-desarrollado-segun-lo-p\/#primaryimage"},"thumbnailUrl":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/wp-content\/uploads\/2019\/12\/jornada-mediciones.jpg","datePublished":"2019-12-05T10:44:27+00:00","description":"La jornada inaugural del Campeonato de Espa\u00f1a de Laser 4.7 juvenil, que hasta el domingo se celebra en la ciudad aut\u00f3noma de Melilla organizado por su Real Club Mar\u00edtimo, se ha desarrollado seg\u00fan lo previsto. Todos los regatistas y equipos auton\u00f3micos se encuentran en Melilla, donde hoy se ha procedido a las mediciones oficiales y a la inscripci\u00f3n de los participantes. En total competir\u00e1n 118 regatistas, de las categor\u00edas sub16 y sub18, representando a diez comunidades aut\u00f3nomas y a la ciudad de Melilla. Las mediciones, junto a los preparativos para la competici\u00f3n y los entrenamientos ha ocupado el tiempo de la flota durante toda la jornada de este mi\u00e9rcoles en el Real Club Maritimo de Melilla. Una jornada en la que una tormenta ha sido la gran protagonista, que ha sorprendido a la flota tanto en el campo de regatas como en el proceso de inscripci\u00f3n. Pero sin incidencias, convirti\u00e9ndose en el aspecto m\u00e1s comentado durante el almuerzo de los regatistas. Desde ma\u00f1ana jueves se suceder\u00e1n cuatro jornadas de regata. Las dos primeras, jueves y viernes, est\u00e1n programadas seis mangas clasificatorias. A partir del s\u00e1bado, la flota quedar\u00e1 dividida en grupo Oro y Plata. En total se decidir\u00e1n cinco t\u00edtulos nacionales, los masculinos y femeninos en sub16 y sub18, adem\u00e1s del campeonato por comunidades aut\u00f3nomas. Para luchar por este \u00faltimo t\u00edtulo, los equipos auton\u00f3micos de Baleares y Comunidad Valenciana son los grandes favoritos. Melilla cuenta con un equipo formado por cuatro regatistas del Real Club Mar\u00edtimo de Melilla. Miguel Due\u00f1as, Pablo Cervilla, Andr\u00e9s Sarri\u00e1 y Miguel Angel Weil -","breadcrumb":{"@id":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/la-jornada-inaugural-del-campeonato-de-espana-de-laser-4-7-juvenil-que-hasta-el-domingo-se-celebra-en-la-ciudad-autonoma-de-melilla-organizado-por-su-real-club-maritimo-se-ha-desarrollado-segun-lo-p\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.realclubmaritimomelilla.es\/clmar\/la-jornada-inaugural-del-campeonato-de-espana-de-laser-4-7-juvenil-que-hasta-el-domingo-se-celebra-en-la-ciudad-autonoma-de-melilla-organizado-por-su-real-club-maritimo-se-ha-desarrollado-segun-lo-p\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/la-jornada-inaugural-del-campeonato-de-espana-de-laser-4-7-juvenil-que-hasta-el-domingo-se-celebra-en-la-ciudad-autonoma-de-melilla-organizado-por-su-real-club-maritimo-se-ha-desarrollado-segun-lo-p\/#primaryimage","url":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/wp-content\/uploads\/2019\/12\/jornada-mediciones.jpg","contentUrl":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/wp-content\/uploads\/2019\/12\/jornada-mediciones.jpg","width":2016,"height":1512},{"@type":"BreadcrumbList","@id":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/la-jornada-inaugural-del-campeonato-de-espana-de-laser-4-7-juvenil-que-hasta-el-domingo-se-celebra-en-la-ciudad-autonoma-de-melilla-organizado-por-su-real-club-maritimo-se-ha-desarrollado-segun-lo-p\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/"},{"@type":"ListItem","position":2,"name":"La jornada inaugural del Campeonato de Espa\u00f1a de Laser 4.7 juvenil, que hasta el domingo se celebra en la ciudad aut\u00f3noma de Melilla organizado por su Real Club Mar\u00edtimo, se ha desarrollado seg\u00fan lo previsto. Todos los regatistas y equipos auton\u00f3micos se encuentran en Melilla, donde hoy se ha procedido a las mediciones oficiales y a la inscripci\u00f3n de los participantes. En total competir\u00e1n 118 regatistas, de las categor\u00edas sub16 y sub18, representando a diez comunidades aut\u00f3nomas y a la ciudad de Melilla. Las mediciones, junto a los preparativos para la competici\u00f3n y los entrenamientos ha ocupado el tiempo de la flota durante toda la jornada de este mi\u00e9rcoles en el Real Club Maritimo de Melilla. Una jornada en la que una tormenta ha sido la gran protagonista, que ha sorprendido a la flota tanto en el campo de regatas como en el proceso de inscripci\u00f3n. Pero sin incidencias, convirti\u00e9ndose en el aspecto m\u00e1s comentado durante el almuerzo de los regatistas. Desde ma\u00f1ana jueves se suceder\u00e1n cuatro jornadas de regata. Las dos primeras, jueves y viernes, est\u00e1n programadas seis mangas clasificatorias. A partir del s\u00e1bado, la flota quedar\u00e1 dividida en grupo Oro y Plata. En total se decidir\u00e1n cinco t\u00edtulos nacionales, los masculinos y femeninos en sub16 y sub18, adem\u00e1s del campeonato por comunidades aut\u00f3nomas. Para luchar por este \u00faltimo t\u00edtulo, los equipos auton\u00f3micos de Baleares y Comunidad Valenciana son los grandes favoritos. Melilla cuenta con un equipo formado por cuatro regatistas del Real Club Mar\u00edtimo de Melilla. Miguel Due\u00f1as, Pablo Cervilla, Andr\u00e9s Sarri\u00e1 y Miguel Angel Weil"}]},{"@type":"WebSite","@id":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/#website","url":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/","name":"Real Club Mar\u00edtimo de Melilla","description":"RCMM","publisher":{"@id":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/#organization"},"alternateName":"RCMM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/#organization","name":"Real Club Mar\u00edtimo de Melilla","alternateName":"RCMM","url":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/#\/schema\/logo\/image\/","url":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/wp-content\/uploads\/logo-club-original-copia.jpg","contentUrl":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/wp-content\/uploads\/logo-club-original-copia.jpg","width":128,"height":89,"caption":"Real Club Mar\u00edtimo de Melilla"},"image":{"@id":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Real-Club-Mar\u00edtimo-de-Melilla-588495841234214\/","https:\/\/x.com\/nauticarcmm","https:\/\/www.instagram.com\/club_maritimo_melilla\/","https:\/\/www.youtube.com\/@realclubmaritimodemelilla4703","https:\/\/es.wikipedia.org\/wiki\/Real_Club_Mar\u00edtimo_de_Melilla"]},{"@type":"Person","@id":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/#\/schema\/person\/ebaa3713496dc6d48c872452e73a8e79","name":"RCMMelilla","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/df1c24789360fb9308735c4ee556fc2bc5bf924bf01e53043b8b97ba272da33c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/df1c24789360fb9308735c4ee556fc2bc5bf924bf01e53043b8b97ba272da33c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/df1c24789360fb9308735c4ee556fc2bc5bf924bf01e53043b8b97ba272da33c?s=96&d=mm&r=g","caption":"RCMMelilla"}}]}},"_links":{"self":[{"href":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/wp-json\/wp\/v2\/posts\/14900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/wp-json\/wp\/v2\/comments?post=14900"}],"version-history":[{"count":1,"href":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/wp-json\/wp\/v2\/posts\/14900\/revisions"}],"predecessor-version":[{"id":14902,"href":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/wp-json\/wp\/v2\/posts\/14900\/revisions\/14902"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/wp-json\/wp\/v2\/media\/14901"}],"wp:attachment":[{"href":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/wp-json\/wp\/v2\/media?parent=14900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/wp-json\/wp\/v2\/categories?post=14900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.realclubmaritimomelilla.es\/clmar\/wp-json\/wp\/v2\/tags?post=14900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}